{"id":10338,"count":1,"description":"","link":"https:\/\/itviec.com\/blog\/tag\/technical-leader-fullstack-developer\/","name":"TECHNICAL LEADER\/ FULLSTACK DEVELOPER","slug":"technical-leader-fullstack-developer","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>TECHNICAL LEADER\/ FULLSTACK DEVELOPER Archives - ITviec Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"vi_VN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TECHNICAL LEADER\/ FULLSTACK DEVELOPER Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itviec.com\/blog\/tag\/technical-leader-fullstack-developer\/\" \/>\n<meta property=\"og:site_name\" content=\"ITviec Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itviec.com\/blog\/wp-content\/uploads\/2016\/10\/homepage3-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"492\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ITviec\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"TECHNICAL LEADER\/ FULLSTACK DEVELOPER Archives - ITviec Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"vi_VN","og_type":"article","og_title":"TECHNICAL LEADER\/ FULLSTACK DEVELOPER Archives","og_url":"https:\/\/itviec.com\/blog\/tag\/technical-leader-fullstack-developer\/","og_site_name":"ITviec Blog","og_image":[{"width":940,"height":492,"url":"https:\/\/itviec.com\/blog\/wp-content\/uploads\/2016\/10\/homepage3-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ITviec","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/itviec.com\/blog\/tag\/technical-leader-fullstack-developer\/","url":"https:\/\/itviec.com\/blog\/tag\/technical-leader-fullstack-developer\/","name":"TECHNICAL LEADER\/ FULLSTACK DEVELOPER Archives - ITviec Blog","isPartOf":{"@id":"https:\/\/itviec.com\/blog\/#website"},"inLanguage":"vi"},{"@type":"WebSite","@id":"https:\/\/itviec.com\/blog\/#website","url":"https:\/\/itviec.com\/blog\/","name":"ITviec Blog","description":"IT Jobs &amp; People in Vietnam","publisher":{"@id":"https:\/\/itviec.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itviec.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"vi"},{"@type":"Organization","@id":"https:\/\/itviec.com\/blog\/#organization","name":"ITviec","url":"https:\/\/itviec.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"vi","@id":"https:\/\/itviec.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/itviec.com\/blog\/wp-content\/uploads\/2018\/12\/itviec-black-square-facebook.png","contentUrl":"https:\/\/itviec.com\/blog\/wp-content\/uploads\/2018\/12\/itviec-black-square-facebook.png","width":1800,"height":1800,"caption":"ITviec"},"image":{"@id":"https:\/\/itviec.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ITviec","https:\/\/x.com\/ITviec","https:\/\/www.linkedin.com\/company\/itviec","https:\/\/www.youtube.com\/channel\/UCYthAQ3bcGr57M_ag5gHDvQ"]}]}},"_links":{"self":[{"href":"https:\/\/itviec.com\/blog\/wp-json\/wp\/v2\/tags\/10338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itviec.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/itviec.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/itviec.com\/blog\/wp-json\/wp\/v2\/posts?tags=10338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}